{"id":96642,"date":"2023-04-20T10:29:00","date_gmt":"2023-04-20T14:29:00","guid":{"rendered":"https:\/\/isarta.com\/infos\/?p=96642"},"modified":"2023-04-20T16:53:39","modified_gmt":"2023-04-20T20:53:39","slug":"recrutement-par-referencement-miracle-ou-mirage","status":"publish","type":"post","link":"https:\/\/isarta.com\/infos\/recrutement-par-referencement-miracle-ou-mirage\/","title":{"rendered":"Recrutement par r\u00e9f\u00e9rencement : miracle ou mirage?"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/pexels-andrea-piacquadio-3762807-683x1024.jpg\" alt=\"\" class=\"wp-image-96718\" width=\"406\" height=\"610\" srcset=\"https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/pexels-andrea-piacquadio-3762807-683x1024.jpg 683w, https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/pexels-andrea-piacquadio-3762807-200x300.jpg 200w, https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/pexels-andrea-piacquadio-3762807-768x1152.jpg 768w, https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/pexels-andrea-piacquadio-3762807-1024x1536.jpg 1024w, https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/pexels-andrea-piacquadio-3762807-1365x2048.jpg 1365w, https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/pexels-andrea-piacquadio-3762807-scaled.jpg 1707w\" sizes=\"(max-width: 406px) 100vw, 406px\" \/><figcaption><em>Le recrutement par r\u00e9f\u00e9rence compte de nombreux avantages&#8230; le probl\u00e8me, c&rsquo;est que de moins en moins de travailleurs acceptent de r\u00e9f\u00e9rer! (Source: Andrea Piacquadio sur Pexel)<\/em><\/figcaption><\/figure>\n<\/div>\n<p>17 avril 2023<\/p>\n<p class=\"has-normal-font-size\"><strong>Le recrutement par r\u00e9f\u00e9rencement est-il une solution \u00ab&nbsp;miracle&nbsp;\u00bb qui est vendue par les professionnels RH? Des experts laissent entendre que cette strat\u00e9gie a ses limites.<\/strong><\/p>\n<p>Il y a quelques ann\u00e9es, <a rel=\"noreferrer noopener\" href=\"https:\/\/www.icims.com\/blog\/how-employee-referrals-impact-retention\/\" data-type=\"URL\" data-id=\"https:\/\/www.icims.com\/blog\/how-employee-referrals-impact-retention\/\" target=\"_blank\">une vaste \u00e9tude effectu\u00e9e par ICIMS en 2018<\/a> a montr\u00e9 tout l\u2019int\u00e9r\u00eat d\u2019embaucher des candidats r\u00e9f\u00e9r\u00e9s par un employ\u00e9 ou un autre candidat. L\u2019\u00e9tude en question, men\u00e9e aupr\u00e8s de 50 entreprises et 91&nbsp;000 employ\u00e9s, r\u00e9v\u00e9lait les statistiques suivantes&nbsp;: &nbsp;<\/p>\n<ul>\n<li>Les employ\u00e9s r\u00e9f\u00e9r\u00e9s restent 70% plus longtemps que les non-r\u00e9f\u00e9r\u00e9s, soit 38 mois versus 22 moins;<\/li>\n<li>Les employ\u00e9s qui r\u00e9f\u00e9rent un candidat restent 20% plus longtemps;<\/li>\n<li>R\u00e9duction de 41% en co\u00fbts de recrutement.<\/li>\n<\/ul>\n<p>\u00c0 la lumi\u00e8re de ces chiffres, on conclut que c&rsquo;est une formule gagnant-gagnant-gagnant, pour le trio candidat-employ\u00e9-employeur. Aussi, selon <a rel=\"noreferrer noopener\" href=\"https:\/\/thetalentboard.wpenginepowered.com\/wp-content\/uploads\/2021\/12\/2021-North-America-CandEs-Research-Report_12-14-2021.Final_.pdf\" data-type=\"URL\" data-id=\"https:\/\/thetalentboard.wpenginepowered.com\/wp-content\/uploads\/2021\/12\/2021-North-America-CandEs-Research-Report_12-14-2021.Final_.pdf\" target=\"_blank\">le Rapport du Talent Board 2021<\/a>, ce type de recrutement repr\u00e9senterait de 20% \u00e0 40% des nouvelles embauches des organisations. <\/p>\n<p><strong>Pas si volontaires que cela&#8230;<\/strong><\/p>\n<p>Or, lors de l&rsquo;\u00e9v\u00e9nement TruMontr\u00e9al 2022, une sp\u00e9cialiste en marque employeur a lanc\u00e9 un pav\u00e9 dans la marre&nbsp;:<\/p>\n<blockquote class=\"wp-block-quote\">\n<p>Cette tendance de l\u2019ambassadeur, j\u2019y ai cru. \u00c7a fait 20 ans que j\u2019y crois. Mais je trouve que, \u00e0 travers les entrevues que je fais, les employ\u00e9s ont vraiment une r\u00e9serve pour r\u00e9f\u00e9rencer des gens de leur r\u00e9seau, a rapport\u00e9 Sylvie Leclerc, qui \u00e9tait, ce jour-l\u00e0, en qu\u00eate d\u2019une r\u00e9ponse \u00e0 cette r\u00e9ticence. Je les trouve pas mal sur le frein, ces Ambassadeurs <em>si actifs en mati\u00e8re de r\u00e9f\u00e9rencement<\/em>&lsquo;.\u00bb<\/p>\n<\/blockquote>\n<p>La professionnelle RH se demandait d&rsquo;ailleurs si la tendance se v\u00e9rifiait, d\u2019un point de vue statistique; \u00e0 savoir que les ambassadeurs se faisaient moins nombreux, ces derni\u00e8res ann\u00e9es, pour amener du sang neuf dans les entreprises.<\/p>\n<p>V\u00e9rification faite, il s\u2019av\u00e8re que cette tendance de recrutement a subi, depuis 2017, un d\u00e9clin global, m\u00eame si, de 2020 \u00e0 2021, il y a eu un l\u00e9ger rebond&nbsp;:<\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"579\" src=\"https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/Capture-de\u0301cran-le-2022-11-14-a\u0300-14.13.15-1024x579.png\" alt=\"\" class=\"wp-image-96646\" srcset=\"https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/Capture-de\u0301cran-le-2022-11-14-a\u0300-14.13.15-1024x579.png 1024w, https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/Capture-de\u0301cran-le-2022-11-14-a\u0300-14.13.15-300x170.png 300w, https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/Capture-de\u0301cran-le-2022-11-14-a\u0300-14.13.15-768x435.png 768w, https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/Capture-de\u0301cran-le-2022-11-14-a\u0300-14.13.15-1536x869.png 1536w, https:\/\/isarta.com\/infos\/wp-content\/uploads\/2022\/11\/Capture-de\u0301cran-le-2022-11-14-a\u0300-14.13.15.png 1930w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption><em>Si on exclut 2021, le r\u00e9f\u00e9rencement comme \u00abvecteur de recrutement\u00bb connait un d\u00e9clin depuis 2017 (Source : <a rel=\"noreferrer noopener\" href=\"https:\/\/thetalentboard.wpenginepowered.com\/wp-content\/uploads\/2021\/12\/2021-North-America-CandEs-Research-Report_12-14-2021.Final_.pdf\" data-type=\"URL\" data-id=\"https:\/\/thetalentboard.wpenginepowered.com\/wp-content\/uploads\/2021\/12\/2021-North-America-CandEs-Research-Report_12-14-2021.Final_.pdf\" target=\"_blank\">2021 North American Candidate Experience Research Report<\/a>)<\/em><\/figcaption><\/figure>\n<p>Selon l\u2019exp\u00e9rience de Sylvie Leclerc, les ambassadeurs attribuent leur r\u00e9ticence \u00e0 r\u00e9f\u00e9rer des candidats sur le compte de la pand\u00e9mie, \u00e0 savoir qu\u2019il manque de candidats partout. Mais aussi, elle se demande si certains ne craignent pas de devoir assumer la responsabilit\u00e9 du nouvel employ\u00e9. &nbsp;<\/p>\n<blockquote class=\"wp-block-quote\">\n<p>Certains disent&nbsp;:&nbsp;je viens d\u2019\u00eatre embauch\u00e9, je vais d\u2019abord faire mes marques et apr\u00e8s je verrai si je recommande quelqu\u2019un, car je mets ma cr\u00e9dibilit\u00e9 en jeu.&nbsp;\u00bb<\/p>\n<\/blockquote>\n<p>Compte tenu de l\u2019extr\u00eame mobilit\u00e9 des travailleurs, il y a lieu de se demander si certains pr\u00e9f\u00e8rent \u00e9viter d\u2019attirer un contact professionnel dans une entreprise qu\u2019ils vont peut-\u00eatre quitter\u2026 dans les prochains mois!<\/p>\n<blockquote class=\"wp-block-quote\">\n<p>C\u2019est une hypoth\u00e8se valide, confirme Sylvie Leclerc. Est-ce parce qu\u2019ils ne savent pas s\u2019ils veulent rester ou s\u2019ils ont besoin de temps pour b\u00e2tir leur lien de confiance avec l\u2019employeur?&nbsp;C\u2019est la question que je me pose. \u00bb<\/p>\n<\/blockquote>\n<p>Conclusion : le recrutement par r\u00e9f\u00e9rencement est merveilleux \u00e0 tous \u00e9gards\u2026 sur papier. Dans le march\u00e9 actuel, les travailleurs se posent probablement trop de questions sur leur propre parcours professionnel pour avoir la t\u00eate \u00e0 convaincre un contact de devenir un coll\u00e8gue.<\/p>\n<blockquote class=\"wp-block-quote\">\n<p>L\u2019effet boomerang, dont on parle beaucoup, je le vois sur le terrain, ajoute Sylvie Leclerc. Il y a plein d\u2019employ\u00e9s qui reviennent chez leur employeur.&nbsp;\u00bb <\/p>\n<\/blockquote>\n<p>La strat\u00e9gie demeure valide, malgr\u00e9 tout. Toutefois, les employeurs doivent voir ses limites et comprendre qu\u2019elle ne peut r\u00e9gler \u00e0 elle seule la crise de talent actuelle.<\/p>\n<hr class=\"wp-block-separator\"\/>\n<p class=\"has-text-align-center\"><strong>Pour vos recrutements, pensez \u00e0 <a rel=\"noreferrer noopener\" href=\"https:\/\/emplois.isarta.com\/\" target=\"_blank\">Isarta Emplois<\/a> !<\/strong><\/p>\n<hr class=\"wp-block-separator\"\/>\n<p><strong>D\u00e9couvrez \u00e9galement nos nouvelles formations sur la marque employeur :<\/strong><\/p>\n<div class=\" content_cards_card content_cards_domain_formations-isarta-com\">\n<div class=\"content_cards_image\">\n            <a class=\"content_cards_image_link\" href=\"https:\/\/formations.isarta.com\/cours\/attraction-de-talents\/40\" target=\"_blank\"><img src=\"https:\/\/formations.isarta.com\/images\/entete.jpg\" alt=\"Formations en RH \/ Marque employeur | Isarta\"><\/a>\n\t\t<\/div>\n<div class=\"content_cards_title\">\n\t\t<a class=\"content_cards_title_link\" href=\"https:\/\/formations.isarta.com\/cours\/attraction-de-talents\/40\" target=\"_blank\">Formations en RH \/ Marque employeur | Isarta<\/a>\n\t<\/div>\n<div class=\"content_cards_description\">\n\t\t<a class=\"content_cards_description_link\" href=\"https:\/\/formations.isarta.com\/cours\/attraction-de-talents\/40\" target=\"_blank\"><\/p>\n<p>Formations en marketing, communication, num\u00e9rique, digital, r\u00e9seaux sociaux. Classes virtuelles (webinaires interactifs \u00e0 distance), en salle ou en entreprise. Montr\u00e9al et partout au Qu\u00e9bec.<\/p>\n<p>\t\t<\/a>\n\t<\/div>\n<\/div>\n<div class=\" content_cards_card content_cards_domain_formations-isarta-com\">\n<div class=\"content_cards_image\">\n            <a class=\"content_cards_image_link\" href=\"https:\/\/formations.isarta.com\/marque-employeur\" target=\"_blank\"><img src=\"https:\/\/formations.isarta.com\/images\/entete.jpg\" alt=\"Formations en RH \/ Marque employeur | Isarta\"><\/a>\n\t\t<\/div>\n<div class=\"content_cards_title\">\n\t\t<a class=\"content_cards_title_link\" href=\"https:\/\/formations.isarta.com\/marque-employeur\" target=\"_blank\">Formations en RH \/ Marque employeur | Isarta<\/a>\n\t<\/div>\n<div class=\"content_cards_description\">\n\t\t<a class=\"content_cards_description_link\" href=\"https:\/\/formations.isarta.com\/marque-employeur\" target=\"_blank\"><\/p>\n<p>Formations en marketing, communication, num\u00e9rique, digital, r\u00e9seaux sociaux. Classes virtuelles (webinaires interactifs \u00e0 distance), en salle ou en entreprise. Montr\u00e9al et partout au Qu\u00e9bec.<\/p>\n<p>\t\t<\/a>\n\t<\/div>\n<\/div>\n<div class=\"likebtn_container\" style=\"clear:both;text-align:center;\"><!-- LikeBtn.com BEGIN --><span class=\"likebtn-wrapper\"  data-identifier=\"post_96642\"  data-site_id=\"5cc1ecd16fd08b776710d1e9\"  data-theme=\"drop\"  data-btn_size=\"100\"  data-icon_l=\"false\"  data-icon_d=\"false\"  data-icon_l_url=\"https:\/\/isarta.com\/infos\/wp-content\/uploads\/2019\/04\/happy.png#64794\"  data-icon_d_url=\"https:\/\/isarta.com\/infos\/wp-content\/uploads\/2019\/04\/sleep.png#64796\"  data-icon_size=\"58\"  data-icon_l_c=\"#771414\"  data-bg_c=\"#ffffff\"  data-bg_c_v=\"#ffffff\"  data-brdr_c=\"#ffffff\"  data-f_size=\"11\"  data-f_family=\"Tahoma\"  data-counter_fs=\"b\"  data-lang=\"fr\"  data-ef_voting=\"wobble\"  data-dislike_enabled=\"false\"  data-counter_type=\"percent\"  data-counter_show=\"false\"  data-tooltip_enabled=\"false\"  data-tooltip_like_show_always=\"true\"  data-white_label=\"true\"  data-i18n_like=\"Aimer \/ Partager\"  data-i18n_dislike=\"Pas aim\u00e9\"  data-style=\"\"  data-unlike_allowed=\"\"  data-show_copyright=\"\"  data-item_url=\"https:\/\/isarta.com\/infos\/recrutement-par-referencement-miracle-ou-mirage\/\"  data-item_title=\"Recrutement par r\u00e9f\u00e9rencement : miracle ou mirage?\"  data-item_image=\"https:\/\/isarta.com\/infos\/wp-content\/uploads\/2023\/04\/referencement.jpeg\"  data-item_date=\"2023-04-20T10:29:00-04:00\"  data-engine=\"WordPress\"  data-plugin_v=\"2.6.54\"  data-prx=\"https:\/\/isarta.com\/infos\/wp-admin\/admin-ajax.php?action=likebtn_prx\"  data-event_handler=\"likebtn_eh\" ><\/span><!-- LikeBtn.com END --><\/p>\n<hr size=\"3\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le recrutement par r\u00e9f\u00e9rencement est-il une solution \u00ab miracle \u00bb qui est vendue par les professionnels RH? Des experts laissent entendre que cette strat\u00e9gie a ses limites.<\/p>\n<div class=\"likebtn_container\" style=\"clear:both;text-align:center;\"><!-- LikeBtn.com BEGIN --><span class=\"likebtn-wrapper\"  data-identifier=\"post_96642\"  data-site_id=\"5cc1ecd16fd08b776710d1e9\"  data-theme=\"drop\"  data-btn_size=\"100\"  data-icon_l=\"false\"  data-icon_d=\"false\"  data-icon_l_url=\"https:\/\/isarta.com\/infos\/wp-content\/uploads\/2019\/04\/happy.png#64794\"  data-icon_d_url=\"https:\/\/isarta.com\/infos\/wp-content\/uploads\/2019\/04\/sleep.png#64796\"  data-icon_size=\"58\"  data-icon_l_c=\"#771414\"  data-bg_c=\"#ffffff\"  data-bg_c_v=\"#ffffff\"  data-brdr_c=\"#ffffff\"  data-f_size=\"11\"  data-f_family=\"Tahoma\"  data-counter_fs=\"b\"  data-lang=\"fr\"  data-ef_voting=\"wobble\"  data-dislike_enabled=\"false\"  data-counter_type=\"percent\"  data-counter_show=\"false\"  data-tooltip_enabled=\"false\"  data-tooltip_like_show_always=\"true\"  data-white_label=\"true\"  data-i18n_like=\"Aimer \/ Partager\"  data-i18n_dislike=\"Pas aim\u00e9\"  data-style=\"\"  data-unlike_allowed=\"\"  data-show_copyright=\"\"  data-item_url=\"https:\/\/isarta.com\/infos\/recrutement-par-referencement-miracle-ou-mirage\/\"  data-item_title=\"Recrutement par r\u00e9f\u00e9rencement : miracle ou mirage?\"  data-item_image=\"https:\/\/isarta.com\/infos\/wp-content\/uploads\/2023\/04\/referencement.jpeg\"  data-item_date=\"2023-04-20T10:29:00-04:00\"  data-engine=\"WordPress\"  data-plugin_v=\"2.6.54\"  data-prx=\"https:\/\/isarta.com\/infos\/wp-admin\/admin-ajax.php?action=likebtn_prx\"  data-event_handler=\"likebtn_eh\" ><\/span><!-- LikeBtn.com END --><hr size=\"3\"><\/div>","protected":false},"author":64,"featured_media":98918,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[175,137,1428,159],"tags":[1487,410,224],"_links":{"self":[{"href":"https:\/\/isarta.com\/infos\/wp-json\/wp\/v2\/posts\/96642"}],"collection":[{"href":"https:\/\/isarta.com\/infos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isarta.com\/infos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isarta.com\/infos\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/isarta.com\/infos\/wp-json\/wp\/v2\/comments?post=96642"}],"version-history":[{"count":40,"href":"https:\/\/isarta.com\/infos\/wp-json\/wp\/v2\/posts\/96642\/revisions"}],"predecessor-version":[{"id":98932,"href":"https:\/\/isarta.com\/infos\/wp-json\/wp\/v2\/posts\/96642\/revisions\/98932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isarta.com\/infos\/wp-json\/wp\/v2\/media\/98918"}],"wp:attachment":[{"href":"https:\/\/isarta.com\/infos\/wp-json\/wp\/v2\/media?parent=96642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isarta.com\/infos\/wp-json\/wp\/v2\/categories?post=96642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isarta.com\/infos\/wp-json\/wp\/v2\/tags?post=96642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}